{"id":4876,"date":"2024-03-15T12:17:51","date_gmt":"2024-03-15T11:17:51","guid":{"rendered":"https:\/\/avocat-lbv.com\/?p=4876"},"modified":"2025-04-22T11:18:45","modified_gmt":"2025-04-22T09:18:45","slug":"il-diritto-dei-brevetti","status":"publish","type":"post","link":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/","title":{"rendered":"Il diritto dei brevetti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il brevetto di invenzione \u00e8 concepito come uno strumento che incentiva l&#8217;innovazione tecnologica e dovrebbe portare al progresso tecnico, il quale sarebbe a sua volta fonte di progresso economico e sociale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gli inventori sarebbero incentivati a innovare e a depositare brevetti poich\u00e9 godrebbero di un&#8217;esclusiva per un periodo determinato che consente di rendere redditizie le spese per la ricerca e lo sviluppo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il brevetto conferisce al suo titolare un diritto esclusivo di sfruttamento territoriale limitato nel tempo. Implica la divulgazione dei mezzi che compongono il brevetto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Francia, i brevetti sono rilasciati dall&#8217;Istituto Nazionale della Propriet\u00e0 Industriale. La Francia \u00e8 anche membro dell&#8217;Ufficio europeo dei brevetti, che rilascia brevetti a livello europeo. L&#8217;Ufficio europeo dei brevetti ha un territorio le cui frontiere non corrispondono esattamente a quelle dell&#8217;Unione europea perch\u00e9 paesi come il Liechtenstein, la Turchia, l&#8217;Albania, la Svizzera, il Regno Unito, l&#8217;Islanda, il Montenegro, la Macedonia del Nord, la Norvegia, la Serbia sono membri dell&#8217;Ufficio europeo dei brevetti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il brevetto garantisce l&#8217;esclusivit\u00e0 solo per un periodo di 20 anni dalla presentazione della domanda di brevetto. Una volta trascorso questo periodo, il brevetto cade nel dominio pubblico. Tuttavia, il diritto francese riconosce la possibilit\u00e0 (specialmente per i farmaci) di ricorrere a un certificato di utilit\u00e0. Questo consente di prolungare il periodo di protezione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sono brevettabili, in tutti i settori tecnologici, le invenzioni nuove che comportano un&#8217;attivit\u00e0 inventiva e sono suscettibili di applicazione industriale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La legge del 1968 ha esplicitamente richiesto che l&#8217;invenzione sia industriale. Questo non era stato esplicitamente indicato nella legge del 5 luglio 1844, anche se il principio era implicito. C&#8217;\u00e8 un requisito di invenzione. La creazione industriale pu\u00f2 riguardare un prodotto (cio\u00e8 un corpo determinato con una composizione meccanica o una struttura chimica particolare che lo distingue dagli altri corpi) o un processo (che consiste in un sistema di intervento di agenti chimici o meccanici la cui attuazione porta all&#8217;ottenimento di un oggetto materiale chiamato prodotto o di un effetto immateriale chiamato risultato). In ogni caso, il risultato non \u00e8 mai protetto. Il processo \u00e8 protetto solo nella sua forma, nella sua funzione e nella sua applicazione. Un mezzo gi\u00e0 noto pu\u00f2 essere utilizzato nell&#8217;ambito di una nuova applicazione. Tuttavia, la protezione non riguarder\u00e0 il mezzo ma l&#8217;applicazione. Anche l&#8217;arrangiamento di mezzi pu\u00f2 essere brevettato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Solo un&#8217;invenzione pu\u00f2 essere brevettata. L&#8217;invenzione \u00e8 una soluzione tecnica a un problema tecnico grazie a mezzi tecnici suscettibili di ripetizione. Per principio, la scoperta non \u00e8 protetta dal diritto dei brevetti. Lo stesso vale per le teorie scientifiche e i metodi matematici. Tuttavia, l&#8217;Ufficio europeo dei brevetti ha stabilito in una controversia &#8220;Hitachi&#8221;, riguardante un sistema di asta online, che il carattere tecnico del dispositivo che implementa un metodo beneficia il metodo stesso. Ci\u00f2 consente di qualificare come invenzione un metodo puramente intellettuale se presentato come accompagnato da alcuni mezzi tecnici.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il diritto francese ha espressamente escluso dai brevetti il software. Questa scelta si basa su considerazioni pratiche poich\u00e9 \u00e8 difficile determinare lo stato della tecnica in questo settore, ma anche su considerazioni di opportunit\u00e0 dato il predominio americano in questo settore (l&#8217;obiettivo era proteggere l&#8217;industria europea del software). Tuttavia, le leggi del 1968 e del 1978 permettono di brevetare i processi che possono coinvolgere software. L&#8217;Ufficio europeo dei brevetti ha avuto l&#8217;opportunit\u00e0 di riconoscere la brevettabilit\u00e0 di un processo implementato sotto il controllo di un software. In questa controversia, l&#8217;invenzione ha apportato un contributo alla tecnica in un settore non escluso dalla brevettabilit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per motivi principalmente sociali, alcune invenzioni sono escluse dalla protezione. Questo vale per i metodi di trattamento terapeutico o chirurgico e per i metodi di diagnosi. Sono anche escluse le invenzioni contrarie alla dignit\u00e0 umana, all&#8217;ordine pubblico o alla morale. Il diritto europeo ha potuto stabilire che sono escluse dalla brevettabilit\u00e0 le invenzioni contrarie alla dignit\u00e0 umana. L&#8217;interpretazione \u00e8 piuttosto ampia dal momento che l&#8217;Ufficio europeo dei brevetti ha stabilito che il concetto di ordine pubblico &#8220;include la protezione dell&#8217;interesse pubblico e l&#8217;integrit\u00e0 fisica degli individui come membri della societ\u00e0&#8221;. Sono quindi escluse dalla brevettabilit\u00e0 &#8220;le invenzioni la cui attuazione rischia di turbare la pace pubblica o l&#8217;ordine sociale o di danneggiare gravemente l&#8217;ambiente&#8221;. \u00c8 anche vietato brevettare il corpo umano o la scoperta di uno dei suoi elementi. Sono altres\u00ec vietati i processi di clonazione umana, i processi di modifica dell&#8217;identit\u00e0 genetica umana e le utilizzazioni di embrioni umani a fini industriali o commerciali. Sono escluse anche le razze animali e le variet\u00e0 vegetali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;invenzione deve essere suscettibile di applicazione industriale. \u00c8 suscettibile di applicazione industriale l&#8217;invenzione il cui oggetto pu\u00f2 essere fabbricato o utilizzato in qualsiasi tipo di industria, compresa l&#8217;agricoltura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;invenzione deve rispettare l&#8217;esigenza di novit\u00e0. L&#8217;invenzione \u00e8 considerata nuova se non \u00e8 compresa nello stato della tecnica. Lo stato della tecnica \u00e8 definito come &#8220;tutto ci\u00f2 che \u00e8 stato reso accessibile al pubblico prima della data di deposito della domanda di brevetto attraverso una descrizione scritta o orale, un uso o qualsiasi altro mezzo&#8221;. La novit\u00e0 deve essere assoluta. Il pubblico \u00e8 definito come qualsiasi persona che non sia tenuta al segreto riguardo alle informazioni che riceve. Concretamente, una persona che ha firmato un accordo di riservatezza non \u00e8 inclusa nella nozione di pubblico. Pu\u00f2 quindi essere utile includere una clausola di riservatezza nel contratto di lavoro del dipendente. L&#8217;esame dell&#8217;accessibilit\u00e0 al pubblico implica che l&#8217;invenzione sia divulgata in modo sufficientemente completo da consentire a un uomo di mestiere di realizzarla e implica anche che il rapporto dell&#8217;uomo di mestiere con l&#8217;invenzione sia sufficientemente caratterizzato da una conoscenza teorica dell&#8217;invenzione. Perch\u00e9 l&#8217;invenzione sia divulgata, non \u00e8 necessario che sia stata portata a conoscenza di una persona determinata. \u00c8 sufficiente che sia stata resa accessibile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le condizioni di divulgazione sono indifferenti. La divulgazione pu\u00f2 quindi derivare da una conferenza, da una commercializzazione, da una pubblicazione (anche su un social network), da un brevetto precedente, ecc. L&#8217;autore della divulgazione \u00e8 indifferente e non \u00e8 importante che la divulgazione sia opera dell&#8217;inventore. Tuttavia, l&#8217;Ufficio europeo dei brevetti rilascia brevetti per &#8220;l&#8217;applicazione di una sostanza o di una composizione per ottenere un medicinale destinato a un uso terapeutico specifico, nuovo e caratterizzato da un&#8217;invenzione&#8221;. Per quanto riguarda le combinazioni, la giurisprudenza sostiene che la novit\u00e0 di un&#8217;invenzione di combinazione pu\u00f2 essere messa in discussione solo da un&#8217;antecedente che riguarda una combinazione identica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 responsabilit\u00e0 di chi sostiene l&#8217;esistenza di un&#8217;antecedente provarlo con tutti i mezzi. \u00c8 quindi possibile fornire la prova attraverso fatture, consegne, verbali di riunioni, testimonianze, ecc&#8230; La prova deve essere fornita al di l\u00e0 di ogni ragionevole dubbio da parte dell&#8217;opponente. Tuttavia, la camera di ricorso tecnico dell&#8217;Ufficio europeo dei brevetti ha recentemente modificato la sua prassi adottando il criterio del bilancio delle probabilit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;attivit\u00e0 deve essere inventiva. Lo stato della tecnica preso in considerazione \u00e8 lo stesso di quello in materia di novit\u00e0. Tuttavia, lo stato della tecnica non tiene conto delle domande di brevetto francesi, europee o internazionali che designano la Francia e non sono ancora state pubblicate alla data di deposito della domanda. Infatti, il rischio di doppia brevettabilit\u00e0 \u00e8 normalmente eliminato dopo l&#8217;esame della novit\u00e0 dell&#8217;invenzione. \u00c8 possibile associare pi\u00f9 antecedenti per dimostrare che un&#8217;invenzione non \u00e8 inventiva. Tuttavia, si presume che l&#8217;uomo del mestiere non conosca l&#8217;intero stato della tecnica. Si tratta di un personaggio astratto che gioca anche un ruolo nell&#8217;esame della sufficienza della descrizione. Si tratta di un professionista che interviene nel settore in cui il problema tecnico \u00e8 risolto dall&#8217;invenzione e posto. Quando l&#8217;invenzione riguarda pi\u00f9 settori tecnici, il giudice definisce un profilo molto specifico delle competenze dell&#8217;uomo del mestiere. Il giudice pu\u00f2 anche stabilire che si tratta di un team. L&#8217;uomo del mestiere non \u00e8 n\u00e9 mediocre n\u00e9 geniale e in ogni caso non \u00e8 dotato di alcuna capacit\u00e0 inventiva. Ha le qualit\u00e0 intellettuali indispensabili per l&#8217;applicazione della tecnica. Ha le conoscenze teoriche e pratiche normali della tecnica interessata. Ci\u00f2 che non va oltre il normale progresso della tecnica ma deriva solo manifestamente e logicamente dallo stato della tecnica, cio\u00e8 ci\u00f2 che non richiede una qualifica o una destrezza pi\u00f9 avanzata di quella che ci si pu\u00f2 ragionevolmente aspettare da un uomo del mestiere (ufficio europeo dei brevetti, direttiva relativa all&#8217;esame, parte G) \u00e8 considerato evidente e non pu\u00f2 essere brevettato. L&#8217;Ufficio europeo dei brevetti ha optato per un metodo chiamato &#8220;problema-soluzioni&#8221;. Si suddivide in 3 fasi:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; In primo luogo, implica determinare lo stato della tecnica pi\u00f9 vicino,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; In secondo luogo, richiede di stabilire il problema tecnico obiettivo e da risolvere,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Infine, richiede di esaminare se l&#8217;invenzione rivendicata, partendo dallo stato della tecnica pi\u00f9 vicino e dal problema obiettivo, sarebbe stata evidente per l&#8217;uomo del mestiere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il giudice francese adotta un metodo simile senza ricorrere alla nozione di stato della tecnica pi\u00f9 vicino. La determinazione dello stato della tecnica pi\u00f9 vicino richiede la ricerca di un documento che divulga un oggetto con caratteristiche simili a quelle dell&#8217;invenzione (ci\u00f2 significa che il documento deve apportare il minor numero possibile di modifiche funzionali e strutturali e che il progetto \u00e8 stato concepito con lo stesso scopo o mira a raggiungere lo stesso obiettivo dell&#8217;invenzione rivendicata). \u00c8 poi necessario determinare il problema tecnico obiettivo e quindi cercare l&#8217;evidenza o la non evidenza della soluzione. Il fatto che l&#8217;invenzione sia costituita da mezzi equivalenti a quelli dello stato della tecnica, \u00e8 generalmente segno di mancanza di attivit\u00e0 inventiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo studio resta a disposizione per qualsiasi domanda avesse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Link utili:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parlamento Europeo&nbsp;: <a href=\"https:\/\/www.europarl.europa.eu\/factsheets\/it\/sheet\/36\/la-proprieta-intellettuale-industriale-e-commerciale\">La propriet\u00e0 intellettuale, industriale e commerciale | Note tematiche sull&#8217;Unione europea | Parlamento Europeo (europa.eu)<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ministero delle imprese e del Made in Italy&nbsp;: <a href=\"https:\/\/uibm.mise.gov.it\/index.php\/it\/brevettare-all-estero\">BREVETTARE ALL&#8217;ESTERO (mise.gov.it)<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sito dall&#8217;Istituto Nazionale della Propriet\u00e0 Industriale: <a href=\"https:\/\/www.inpi.fr\/co\/prucedure-in-linea\/brevetti\">Brevetti | INPI.fr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il brevetto di invenzione \u00e8 concepito come uno strumento che incentiva l&#8217;innovazione tecnologica e dovrebbe portare al progresso tecnico, il quale sarebbe a sua volta fonte di progresso economico e sociale. Gli inventori sarebbero incentivati a innovare e a depositare brevetti poich\u00e9 godrebbero di un&#8217;esclusiva per un periodo determinato che consente di rendere redditizie le [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4872,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[],"class_list":["post-4876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diritto-della-proprieta-intelletuale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il diritto dei brevetti - LBV Avocat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il diritto dei brevetti - LBV Avocat\" \/>\n<meta property=\"og:description\" content=\"Il brevetto di invenzione \u00e8 concepito come uno strumento che incentiva l&#8217;innovazione tecnologica e dovrebbe portare al progresso tecnico, il quale sarebbe a sua volta fonte di progresso economico e sociale. Gli inventori sarebbero incentivati a innovare e a depositare brevetti poich\u00e9 godrebbero di un&#8217;esclusiva per un periodo determinato che consente di rendere redditizie le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/\" \/>\n<meta property=\"og:site_name\" content=\"LBV Avocat\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/avocatLBV\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-15T11:17:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-22T09:18:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2024\/03\/brevet.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"mleborloch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CabinetLBV\" \/>\n<meta name=\"twitter:site\" content=\"@CabinetLBV\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mleborloch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/il-diritto-dei-brevetti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/il-diritto-dei-brevetti\\\/\"},\"author\":{\"name\":\"mleborloch\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#\\\/schema\\\/person\\\/9dd661f2771e230c3a56bfe95e692e39\"},\"headline\":\"Il diritto dei brevetti\",\"datePublished\":\"2024-03-15T11:17:51+00:00\",\"dateModified\":\"2025-04-22T09:18:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/il-diritto-dei-brevetti\\\/\"},\"wordCount\":1679,\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/il-diritto-dei-brevetti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/brevet.png\",\"articleSection\":[\"Diritto della propriet\u00e0 intelletuale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/il-diritto-dei-brevetti\\\/\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/il-diritto-dei-brevetti\\\/\",\"name\":\"Il diritto dei brevetti - LBV Avocat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/il-diritto-dei-brevetti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/il-diritto-dei-brevetti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/brevet.png\",\"datePublished\":\"2024-03-15T11:17:51+00:00\",\"dateModified\":\"2025-04-22T09:18:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/il-diritto-dei-brevetti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/il-diritto-dei-brevetti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/il-diritto-dei-brevetti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/brevet.png\",\"contentUrl\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/brevet.png\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/il-diritto-dei-brevetti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/cabinet-davocat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il diritto dei brevetti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#website\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/\",\"name\":\"LBV Avocat\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-lbv.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#organization\",\"name\":\"LBV Avocat\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo-blanc.svg\",\"contentUrl\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo-blanc.svg\",\"width\":227,\"height\":52,\"caption\":\"LBV Avocat\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/avocatLBV\\\/\",\"https:\\\/\\\/x.com\\\/CabinetLBV\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#\\\/schema\\\/person\\\/9dd661f2771e230c3a56bfe95e692e39\",\"name\":\"mleborloch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec337fca4185d6de32abb4a2fd4bf2fd723bc16f38f8fac6d7882c59b2ca3bcf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec337fca4185d6de32abb4a2fd4bf2fd723bc16f38f8fac6d7882c59b2ca3bcf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec337fca4185d6de32abb4a2fd4bf2fd723bc16f38f8fac6d7882c59b2ca3bcf?s=96&d=mm&r=g\",\"caption\":\"mleborloch\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il diritto dei brevetti - LBV Avocat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/","og_locale":"it_IT","og_type":"article","og_title":"Il diritto dei brevetti - LBV Avocat","og_description":"Il brevetto di invenzione \u00e8 concepito come uno strumento che incentiva l&#8217;innovazione tecnologica e dovrebbe portare al progresso tecnico, il quale sarebbe a sua volta fonte di progresso economico e sociale. Gli inventori sarebbero incentivati a innovare e a depositare brevetti poich\u00e9 godrebbero di un&#8217;esclusiva per un periodo determinato che consente di rendere redditizie le [&hellip;]","og_url":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/","og_site_name":"LBV Avocat","article_publisher":"https:\/\/www.facebook.com\/avocatLBV\/","article_published_time":"2024-03-15T11:17:51+00:00","article_modified_time":"2025-04-22T09:18:45+00:00","og_image":[{"url":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2024\/03\/brevet.png","width":1024,"height":1024,"type":"image\/png"}],"author":"mleborloch","twitter_card":"summary_large_image","twitter_creator":"@CabinetLBV","twitter_site":"@CabinetLBV","twitter_misc":{"Scritto da":"mleborloch","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/#article","isPartOf":{"@id":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/"},"author":{"name":"mleborloch","@id":"https:\/\/avocat-lbv.com\/#\/schema\/person\/9dd661f2771e230c3a56bfe95e692e39"},"headline":"Il diritto dei brevetti","datePublished":"2024-03-15T11:17:51+00:00","dateModified":"2025-04-22T09:18:45+00:00","mainEntityOfPage":{"@id":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/"},"wordCount":1679,"publisher":{"@id":"https:\/\/avocat-lbv.com\/#organization"},"image":{"@id":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/#primaryimage"},"thumbnailUrl":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2024\/03\/brevet.png","articleSection":["Diritto della propriet\u00e0 intelletuale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/","url":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/","name":"Il diritto dei brevetti - LBV Avocat","isPartOf":{"@id":"https:\/\/avocat-lbv.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/#primaryimage"},"image":{"@id":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/#primaryimage"},"thumbnailUrl":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2024\/03\/brevet.png","datePublished":"2024-03-15T11:17:51+00:00","dateModified":"2025-04-22T09:18:45+00:00","breadcrumb":{"@id":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/#primaryimage","url":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2024\/03\/brevet.png","contentUrl":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2024\/03\/brevet.png","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-lbv.com\/it\/il-diritto-dei-brevetti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-lbv.com\/it\/cabinet-davocat\/"},{"@type":"ListItem","position":2,"name":"Il diritto dei brevetti"}]},{"@type":"WebSite","@id":"https:\/\/avocat-lbv.com\/#website","url":"https:\/\/avocat-lbv.com\/","name":"LBV Avocat","description":"","publisher":{"@id":"https:\/\/avocat-lbv.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-lbv.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/avocat-lbv.com\/#organization","name":"LBV Avocat","url":"https:\/\/avocat-lbv.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/avocat-lbv.com\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2019\/04\/logo-blanc.svg","contentUrl":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2019\/04\/logo-blanc.svg","width":227,"height":52,"caption":"LBV Avocat"},"image":{"@id":"https:\/\/avocat-lbv.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/avocatLBV\/","https:\/\/x.com\/CabinetLBV"]},{"@type":"Person","@id":"https:\/\/avocat-lbv.com\/#\/schema\/person\/9dd661f2771e230c3a56bfe95e692e39","name":"mleborloch","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ec337fca4185d6de32abb4a2fd4bf2fd723bc16f38f8fac6d7882c59b2ca3bcf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ec337fca4185d6de32abb4a2fd4bf2fd723bc16f38f8fac6d7882c59b2ca3bcf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec337fca4185d6de32abb4a2fd4bf2fd723bc16f38f8fac6d7882c59b2ca3bcf?s=96&d=mm&r=g","caption":"mleborloch"}}]}},"featured_image_src":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2024\/03\/brevet.png","featured_image_src_square":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2024\/03\/brevet.png","author_info":{"display_name":"mleborloch","author_link":"https:\/\/avocat-lbv.com\/it\/author\/mleborloch\/"},"_links":{"self":[{"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/posts\/4876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/comments?post=4876"}],"version-history":[{"count":1,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/posts\/4876\/revisions"}],"predecessor-version":[{"id":4877,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/posts\/4876\/revisions\/4877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/media\/4872"}],"wp:attachment":[{"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/media?parent=4876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/categories?post=4876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/tags?post=4876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}