{"id":3148,"date":"2022-08-30T09:43:00","date_gmt":"2022-08-30T07:43:00","guid":{"rendered":"https:\/\/avocat-lbv.com\/?p=3148"},"modified":"2025-04-22T11:20:07","modified_gmt":"2025-04-22T09:20:07","slug":"consumo-di-cbd-e-cannabis","status":"publish","type":"post","link":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/","title":{"rendered":"<strong><u>CONSUMO DI CBD E CANNABIS<\/u><\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il regime applicabile al consumo di cannabis e CBD appare spesso confuso. Occorre tuttavia mostrare rigore e distinguere nettamente tra i due prodotti (I). In caso di arresto per consumo di stupefacenti, la persona arrestata ed eventualmente posta in custodia cautelare deve prestare attenzione al regolare svolgimento della procedura (II).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I \u2013 La distinzione legale tra CBD e cannabis<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;elenco degli stupefacenti \u00e8 fissato esaurientemente nella Convenzione unica sugli stupefacenti del 1961. Conformemente alle disposizioni dell&#8217;articolo 55 della Costituzione francese, questa convenzione ha un valore superiore alle leggi e si applica direttamente nel diritto francese. Tuttavia, la convenzione non prende di mira il CBD ma solo il cannabis. Ne consegue che solo la cannabis pu\u00f2 essere qualificata come narcotico nella legge francese e non il CBD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Corte di giustizia dell&#8217;Unione Europea, le cui decisioni sono direttamente applicabili nel diritto francese, ha ritenuto nella sentenza KANAVAPE del 19 novembre 2020 (C-663\/18) che la CBD non include un principio psicoattivo allo stato attuale della scienza conoscenza e che sarebbe contrario allo scopo e allo spirito generale della Convenzione includere la CBD nella definizione di stupefacenti (punto 75).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Corte di giustizia dell&#8217;Unione Europea ha anche ricordato che &#8220;la CBD nella causa principale non costituisce un narcotico ai sensi della Convenzione Unica&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Convenzione e la Corte di Giustizia dell&#8217;Unione Europea parlano chiaro: il CBD non \u00e8 un narcotico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel caso in cui gli stati membri dell&#8217;Unione Europea optino per restrizioni alla vendita e all&#8217;uso del CBD, la Corte di Giustizia dell&#8217;Unione Europea ritiene necessario rispettare il principio di proporzionalit\u00e0 e di conseguenza i mezzi scelti dagli Stati devono essere limitati a quanto effettivamente necessario per garantire la tutela della salute pubblica ed essere proporzionati all&#8217;obiettivo cos\u00ec perseguito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tuttavia, la Commissione sugli stupefacenti e gli psicofarmaci nella sua sessione n. 11 del 25 giugno 2015 ha ritenuto che il CBD in generale non presenti alcun rischio importante associato al suo consumo. Ne consegue che i limiti possono essere solo circoscritti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Concretamente, \u00e8 possibile vendere, consumare e persino registrare un marchio di CBD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Francia, se la legalizzazione del cannabis sembra ancora lontana, \u00e8 chiaro che gli studi tendono a sottoporre il consumo di cannabis a un regime dispregiativo al consumo di stupefacenti. Ci\u00f2 deriva non solo dal fatto che il cannabis \u00e8 considerato una &#8220;droga leggera&#8221;, ma anche dal desiderio di sbloccare i tribunali, in particolare i tribunali penali, che sono sopraffatti da casi relativi alla cannabis. Viene cos\u00ec condotto un esperimento volto a criminalizzare il consumo di cannabis al fine di accelerare e facilitare le sanzioni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel caso in cui una persona venga arrestata per consumo di CBD, cannabis o altro prodotto narcotico, sarebbe opportuno rimanere molto attenti alla procedura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">II \u2013 La procedura legale per il consumo di CBD, cannabis e altri narcotici: alcuni consigli<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In caso di arresto per consumo di droga, le forze dell&#8217;ordine sono tenute ad effettuare un primo test della saliva. Se il primo test \u00e8 positivo, la polizia dovr\u00e0 effettuare un secondo test della saliva. Se il secondo test \u00e8 positivo, l&#8217;arrestato pu\u00f2, una volta informato dei risultati del test, richiedere un secondo parere entro 5 giorni. \u00c8 preferibile richiedere questo secondo parere perch\u00e9, in mancanza, i Giudici potrebbero ritenere che si tratti di un riconoscimento implicito della sussistenza del reato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se la persona ha consumato stupefacenti, la sua unica speranza risiede in un possibile errore che potrebbe verificarsi. Questo sarebbe il caso se tra i due test, uno dei due fosse positivo e l&#8217;altro negativo, cos\u00ec che ci sarebbe un dubbio di cui beneficia il convenuto. Lo stesso varrebbe se il perito dietro l&#8217;analisi non fosse un esperto della Corte d&#8217;Appello competente. E, infine, non \u00e8 da escludere che il secondo test dia esito pi\u00f9 favorevole all&#8217;imputato (se i test sono sempre pi\u00f9 precisi possono comunque verificarsi falsi positivi).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In termini di CBD, alcuni test utilizzati distinguono in modo affidabile tra consumo di cannabis e CBD quando quest&#8217;ultimo viene consumato sotto forma di gocce. Gli studi sollevano dubbi sull&#8217;affidabilit\u00e0 di questi test quando il CBD viene consumato per inalazione (cio\u00e8 quando fumato). In questo caso, rimane un ragionevole dubbio quando il consumatore di CBD \u00e8 risultato positivo alla cannabis. Questo dubbio deve giovargli.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inoltre, se il livello di consumo di stupefacenti non \u00e8 ritenuto dalla Corte di Cassazione come reato (basta essere positivo al test), il Codice di sanit\u00e0 pubblica ha stabilito soglie di tolleranza per i test che devono essere rispettati e comunicati nella procedura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se, infine, non si pu\u00f2 ottenere nullit\u00e0 in sede dibattimentale, sar\u00e0 necessario riflettere sulla questione della personalizzazione della sentenza. La persona perseguita dovrebbe quindi fornire la prova dell&#8217;esistenza di un lavoro (idealmente un contratto a tempo indeterminato), di un alloggio in affitto o di propriet\u00e0 e di un ambiente familiare e amichevole (potrebbe essere utile fornire prova dell&#8217;esistenza di un PACS, di matrimonio o di aver avuto figli).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per qualsiasi consiglio non esitate a contattare l&#8217;azienda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il regime applicabile al consumo di cannabis e CBD appare spesso confuso. Occorre tuttavia mostrare rigore e distinguere nettamente tra i due prodotti (I). In caso di arresto per consumo di stupefacenti, la persona arrestata ed eventualmente posta in custodia cautelare deve prestare attenzione al regolare svolgimento della procedura (II). I \u2013 La distinzione legale [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2565,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[],"class_list":["post-3148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diritto-penale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONSUMO DI CBD E CANNABIS - LBV Avocat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONSUMO DI CBD E CANNABIS - LBV Avocat\" \/>\n<meta property=\"og:description\" content=\"Il regime applicabile al consumo di cannabis e CBD appare spesso confuso. Occorre tuttavia mostrare rigore e distinguere nettamente tra i due prodotti (I). In caso di arresto per consumo di stupefacenti, la persona arrestata ed eventualmente posta in custodia cautelare deve prestare attenzione al regolare svolgimento della procedura (II). I \u2013 La distinzione legale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/\" \/>\n<meta property=\"og:site_name\" content=\"LBV Avocat\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/avocatLBV\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-30T07:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-22T09:20:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2022\/08\/pexels-kindel-media-7667731-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mleborloch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CabinetLBV\" \/>\n<meta name=\"twitter:site\" content=\"@CabinetLBV\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"mleborloch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/consumo-di-cbd-e-cannabis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/consumo-di-cbd-e-cannabis\\\/\"},\"author\":{\"name\":\"mleborloch\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#\\\/schema\\\/person\\\/9dd661f2771e230c3a56bfe95e692e39\"},\"headline\":\"CONSUMO DI CBD E CANNABIS\",\"datePublished\":\"2022-08-30T07:43:00+00:00\",\"dateModified\":\"2025-04-22T09:20:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/consumo-di-cbd-e-cannabis\\\/\"},\"wordCount\":821,\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/consumo-di-cbd-e-cannabis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-kindel-media-7667731-scaled.jpg\",\"articleSection\":[\"Diritto p\u00e9nale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/consumo-di-cbd-e-cannabis\\\/\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/consumo-di-cbd-e-cannabis\\\/\",\"name\":\"CONSUMO DI CBD E CANNABIS - LBV Avocat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/consumo-di-cbd-e-cannabis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/consumo-di-cbd-e-cannabis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-kindel-media-7667731-scaled.jpg\",\"datePublished\":\"2022-08-30T07:43:00+00:00\",\"dateModified\":\"2025-04-22T09:20:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/consumo-di-cbd-e-cannabis\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/consumo-di-cbd-e-cannabis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/consumo-di-cbd-e-cannabis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-kindel-media-7667731-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-kindel-media-7667731-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/consumo-di-cbd-e-cannabis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-lbv.com\\\/it\\\/cabinet-davocat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONSUMO DI CBD E CANNABIS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#website\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/\",\"name\":\"LBV Avocat\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-lbv.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#organization\",\"name\":\"LBV Avocat\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo-blanc.svg\",\"contentUrl\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo-blanc.svg\",\"width\":227,\"height\":52,\"caption\":\"LBV Avocat\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/avocatLBV\\\/\",\"https:\\\/\\\/x.com\\\/CabinetLBV\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#\\\/schema\\\/person\\\/9dd661f2771e230c3a56bfe95e692e39\",\"name\":\"mleborloch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec337fca4185d6de32abb4a2fd4bf2fd723bc16f38f8fac6d7882c59b2ca3bcf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec337fca4185d6de32abb4a2fd4bf2fd723bc16f38f8fac6d7882c59b2ca3bcf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ec337fca4185d6de32abb4a2fd4bf2fd723bc16f38f8fac6d7882c59b2ca3bcf?s=96&d=mm&r=g\",\"caption\":\"mleborloch\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONSUMO DI CBD E CANNABIS - LBV Avocat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/","og_locale":"it_IT","og_type":"article","og_title":"CONSUMO DI CBD E CANNABIS - LBV Avocat","og_description":"Il regime applicabile al consumo di cannabis e CBD appare spesso confuso. Occorre tuttavia mostrare rigore e distinguere nettamente tra i due prodotti (I). In caso di arresto per consumo di stupefacenti, la persona arrestata ed eventualmente posta in custodia cautelare deve prestare attenzione al regolare svolgimento della procedura (II). I \u2013 La distinzione legale [&hellip;]","og_url":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/","og_site_name":"LBV Avocat","article_publisher":"https:\/\/www.facebook.com\/avocatLBV\/","article_published_time":"2022-08-30T07:43:00+00:00","article_modified_time":"2025-04-22T09:20:07+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2022\/08\/pexels-kindel-media-7667731-scaled.jpg","type":"image\/jpeg"}],"author":"mleborloch","twitter_card":"summary_large_image","twitter_creator":"@CabinetLBV","twitter_site":"@CabinetLBV","twitter_misc":{"Scritto da":"mleborloch","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/#article","isPartOf":{"@id":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/"},"author":{"name":"mleborloch","@id":"https:\/\/avocat-lbv.com\/#\/schema\/person\/9dd661f2771e230c3a56bfe95e692e39"},"headline":"CONSUMO DI CBD E CANNABIS","datePublished":"2022-08-30T07:43:00+00:00","dateModified":"2025-04-22T09:20:07+00:00","mainEntityOfPage":{"@id":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/"},"wordCount":821,"publisher":{"@id":"https:\/\/avocat-lbv.com\/#organization"},"image":{"@id":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/#primaryimage"},"thumbnailUrl":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2022\/08\/pexels-kindel-media-7667731-scaled.jpg","articleSection":["Diritto p\u00e9nale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/","url":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/","name":"CONSUMO DI CBD E CANNABIS - LBV Avocat","isPartOf":{"@id":"https:\/\/avocat-lbv.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/#primaryimage"},"image":{"@id":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/#primaryimage"},"thumbnailUrl":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2022\/08\/pexels-kindel-media-7667731-scaled.jpg","datePublished":"2022-08-30T07:43:00+00:00","dateModified":"2025-04-22T09:20:07+00:00","breadcrumb":{"@id":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/#primaryimage","url":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2022\/08\/pexels-kindel-media-7667731-scaled.jpg","contentUrl":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2022\/08\/pexels-kindel-media-7667731-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-lbv.com\/it\/consumo-di-cbd-e-cannabis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-lbv.com\/it\/cabinet-davocat\/"},{"@type":"ListItem","position":2,"name":"CONSUMO DI CBD E CANNABIS"}]},{"@type":"WebSite","@id":"https:\/\/avocat-lbv.com\/#website","url":"https:\/\/avocat-lbv.com\/","name":"LBV Avocat","description":"","publisher":{"@id":"https:\/\/avocat-lbv.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-lbv.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/avocat-lbv.com\/#organization","name":"LBV Avocat","url":"https:\/\/avocat-lbv.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/avocat-lbv.com\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2019\/04\/logo-blanc.svg","contentUrl":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2019\/04\/logo-blanc.svg","width":227,"height":52,"caption":"LBV Avocat"},"image":{"@id":"https:\/\/avocat-lbv.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/avocatLBV\/","https:\/\/x.com\/CabinetLBV"]},{"@type":"Person","@id":"https:\/\/avocat-lbv.com\/#\/schema\/person\/9dd661f2771e230c3a56bfe95e692e39","name":"mleborloch","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ec337fca4185d6de32abb4a2fd4bf2fd723bc16f38f8fac6d7882c59b2ca3bcf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ec337fca4185d6de32abb4a2fd4bf2fd723bc16f38f8fac6d7882c59b2ca3bcf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec337fca4185d6de32abb4a2fd4bf2fd723bc16f38f8fac6d7882c59b2ca3bcf?s=96&d=mm&r=g","caption":"mleborloch"}}]}},"featured_image_src":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2022\/08\/pexels-kindel-media-7667731-scaled.jpg","featured_image_src_square":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2022\/08\/pexels-kindel-media-7667731-scaled.jpg","author_info":{"display_name":"mleborloch","author_link":"https:\/\/avocat-lbv.com\/it\/author\/mleborloch\/"},"_links":{"self":[{"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/posts\/3148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/comments?post=3148"}],"version-history":[{"count":1,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/posts\/3148\/revisions"}],"predecessor-version":[{"id":3149,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/posts\/3148\/revisions\/3149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/media\/2565"}],"wp:attachment":[{"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/media?parent=3148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/categories?post=3148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avocat-lbv.com\/it\/wp-json\/wp\/v2\/tags?post=3148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}