{"id":42,"count":3,"description":"","link":"https:\/\/avocat-lbv.com\/en\/category\/criminal-law\/","name":"Criminal law","slug":"criminal-law","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Criminal law - LBV Avocat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-lbv.com\/en\/category\/criminal-law\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Criminal law - LBV Avocat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-lbv.com\/en\/category\/criminal-law\/\" \/>\n<meta property=\"og:site_name\" content=\"LBV Avocat\" \/>\n<meta property=\"og:image\" content=\"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2019\/04\/actualite.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CabinetLBV\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/en\\\/category\\\/criminal-law\\\/\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/en\\\/category\\\/criminal-law\\\/\",\"name\":\"Archives des Criminal law - LBV Avocat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/en\\\/category\\\/criminal-law\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/en\\\/category\\\/criminal-law\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-lbv.com\\\/en\\\/cabinet-davocat\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Criminal law\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#website\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/\",\"name\":\"LBV Avocat\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-lbv.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#organization\",\"name\":\"LBV Avocat\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo-blanc.svg\",\"contentUrl\":\"https:\\\/\\\/avocat-lbv.com\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo-blanc.svg\",\"width\":227,\"height\":52,\"caption\":\"LBV Avocat\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-lbv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/avocatLBV\\\/\",\"https:\\\/\\\/x.com\\\/CabinetLBV\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Criminal law - LBV Avocat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-lbv.com\/en\/category\/criminal-law\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Criminal law - LBV Avocat","og_url":"https:\/\/avocat-lbv.com\/en\/category\/criminal-law\/","og_site_name":"LBV Avocat","og_image":[{"width":2000,"height":1333,"url":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2019\/04\/actualite.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CabinetLBV","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/avocat-lbv.com\/en\/category\/criminal-law\/","url":"https:\/\/avocat-lbv.com\/en\/category\/criminal-law\/","name":"Archives des Criminal law - LBV Avocat","isPartOf":{"@id":"https:\/\/avocat-lbv.com\/#website"},"breadcrumb":{"@id":"https:\/\/avocat-lbv.com\/en\/category\/criminal-law\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-lbv.com\/en\/category\/criminal-law\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-lbv.com\/en\/cabinet-davocat\/"},{"@type":"ListItem","position":2,"name":"Criminal law"}]},{"@type":"WebSite","@id":"https:\/\/avocat-lbv.com\/#website","url":"https:\/\/avocat-lbv.com\/","name":"LBV Avocat","description":"","publisher":{"@id":"https:\/\/avocat-lbv.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-lbv.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/avocat-lbv.com\/#organization","name":"LBV Avocat","url":"https:\/\/avocat-lbv.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/avocat-lbv.com\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2019\/04\/logo-blanc.svg","contentUrl":"https:\/\/avocat-lbv.com\/wp-content\/uploads\/2019\/04\/logo-blanc.svg","width":227,"height":52,"caption":"LBV Avocat"},"image":{"@id":"https:\/\/avocat-lbv.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/avocatLBV\/","https:\/\/x.com\/CabinetLBV"]}]}},"_links":{"self":[{"href":"https:\/\/avocat-lbv.com\/en\/wp-json\/wp\/v2\/categories\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-lbv.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/avocat-lbv.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/avocat-lbv.com\/en\/wp-json\/wp\/v2\/posts?categories=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}